{"id":2289,"date":"2022-03-25T13:33:04","date_gmt":"2022-03-25T12:33:04","guid":{"rendered":"https:\/\/flutteracademy.app\/?p=2289"},"modified":"2026-03-31T16:03:12","modified_gmt":"2026-03-31T14:03:12","slug":"gitflow-es-parte-de-tu-equipo","status":"publish","type":"post","link":"https:\/\/lacedemon.com\/en\/gitflow-es-parte-de-tu-equipo\/","title":{"rendered":"Gitflow es parte de tu equipo"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Cuando trabajas sobre un proyecto cada vez que guardas unos cambios o modificaciones generas una versi\u00f3n del mismo. Antes ten\u00edas 2 opciones: o machabas las versiones anteriores y perd\u00edas informaci\u00f3n, o guardabas cada versi\u00f3n de manera independiente, lo que al final resultaba poco pr\u00e1ctico y operativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La soluci\u00f3n est\u00e1 en poder trabajar en un mismo espacio en donde puedas almacenar todo este hist\u00f3rico de versiones de manera ordenada, que te permita consultarlas o recuperarlas, sin miedo a da\u00f1ar en lo que est\u00e9s trabajando. Y cuando formas parte de un equipo esta necesidad se hace urgente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GitHub<\/strong> es la plataforma favorita de los desarrolladores para crear y alojar sus proyectos ya que dispone de funcionalidades colaborativas perfectas para trabajar en equipo, aunque tambi\u00e9n pueden crearse proyectos privados.&nbsp; En esta plataforma puedes alojar el proyecto, descargarlo, revisarlo, crear variaciones, etc. y sin pisar tu trabajo anterior o el de los miembros de tu equipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GitHub trabaja con la herramienta <strong>Git<\/strong>, uno de los <strong>sistemas de control de versiones<\/strong> m\u00e1s utilizado por los <strong>desarrolladores de software<\/strong> que realiza la funci\u00f3n del<strong> control de versiones de c\u00f3digo<\/strong> de una forma distribuida. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Principales virtudes de Git<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Es multiplataforma&nbsp;<\/li><li>Permite mantener un historial completo de las versiones<\/li><li>Es r\u00e1pida y te puedes mover por las versiones de manera muy \u00e1gil&nbsp;<\/li><li>Puedes comparar el c\u00f3digo entre versiones, restaurar antiguas o fusionar cambios<\/li><li>Est\u00e1 <strong>organizado en ramas<\/strong> para mantener por un lado el core del proyecto y a la vez desarrollar las partes de manera independiente y que luego se puedan fusionar, depurar los bugs, etc.<\/li><li>Tambi\u00e9n puedes identificar el estado en el que se encuentra proyecto: preparado para una revisi\u00f3n, modificado cuando se han realizado los cambios acordados tras la revisi\u00f3n y confirmado ya est\u00e1n aprobados los cambios y va a una nueva revisi\u00f3n o es definitivo.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Git-flow<\/strong> es el <strong>flujo de trabajo<\/strong> con el que trabajas en Git: es un conjunto de extensiones que te ofrece comandos de alto nivel para operar en repositorios que se basan en el modelo de ramificaciones. De esta manera proporciona un gran control y organizaci\u00f3n dentro del proceso de integraci\u00f3n continua. Adem\u00e1s ayuda a aumentar la velocidad de entrega de c\u00f3digo terminado al equipo de pruebas, logra disminuir los errores humanos cuando se mezclan de las ramas, quita la dependencia de funcionalidades cuando se va a entregar c\u00f3digo para ponerlo en producci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cuando utilizar Gitflow<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si te preguntas cuando puedes o debes usar Gitflow, yo te aconsejar\u00eda que lo usaras pr\u00e1cticamente siempre y sobre todo cuando:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sois 2 o m\u00e1s personas en el equipo<\/li><li>Utiliz\u00e1is metodolog\u00edas \u00e1giles<\/li><li>Tu proyecto es complejo<\/li><li>Realiz\u00e1is cambios o modificaciones de manera frecuente<\/li><li>Si necesitas actualizaciones r\u00e1pidas, constantes y seguras de los cambios que implementas<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para implementar Git Flow en tu proyecto lo que debes hacer es organizarlo y plantearlo en una estructura de ramas en las que existen 2 principales:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>master<\/strong> donde est\u00e1 el proyecto original y no se toca, salvo para colocar las versiones definitivas<\/li><li><strong>develop <\/strong>donde haces una copia del master y sobre la que se va a trabajar.&nbsp;<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Las ramas siguientes son las que se utilizan de manera operativa:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>hotfix branche<\/strong>: rama que se crea para la solucionar incidentes<\/li><li><strong>features brances<\/strong>:&nbsp; creada a partir de develop para los desarrollos de nuevas funcionalidades<\/li><li><strong>releases branches<\/strong>: rama que se utiliza para las entregas a producci\u00f3n o ambiente real.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Los miembros del equipo acuden al develop para llevar a sus terminales aquello su de trabajo creando sus propias features branches. Despu\u00e9s crean release branches para hacer las pruebas y entregarlas a develop cuando est\u00e9n listas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo estar\u00e1 finalizado cuando develop integre el proyecto en master.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"326\" src=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/Captura-de-pantalla-2022-03-17-a-las-11.11.34.png?resize=650%2C326&#038;ssl=1\" alt=\"Gitflow\" class=\"wp-image-2301\" srcset=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/Captura-de-pantalla-2022-03-17-a-las-11.11.34.png?w=650&amp;ssl=1 650w, https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/Captura-de-pantalla-2022-03-17-a-las-11.11.34.png?resize=300%2C150&amp;ssl=1 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-2-2.png?resize=600%2C300&#038;ssl=1\" alt=\"\" class=\"wp-image-2333\" srcset=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-2-2.png?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-2-2.png?resize=300%2C150&amp;ssl=1 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"534\" height=\"804\" src=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-3.png?resize=534%2C804&#038;ssl=1\" alt=\"Gitflow\" class=\"wp-image-2297\" srcset=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-3.png?w=534&amp;ssl=1 534w, https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-3.png?resize=199%2C300&amp;ssl=1 199w\" sizes=\"(max-width: 534px) 100vw, 534px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"809\" src=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-4-1.png?resize=600%2C809&#038;ssl=1\" alt=\"\" class=\"wp-image-2334\" srcset=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-4-1.png?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-4-1.png?resize=222%2C300&amp;ssl=1 222w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-5-1.png?resize=600%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-2335\" srcset=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-5-1.png?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-5-1.png?resize=225%2C300&amp;ssl=1 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"445\" src=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-6-2.png?resize=600%2C445&#038;ssl=1\" alt=\"Gitflow\" class=\"wp-image-2336\" srcset=\"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-6-2.png?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/git-flow-6-2.png?resize=300%2C223&amp;ssl=1 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Gitflow es la soluci\u00f3n para poder trabajar en equipo en un proyecto sin perder informaci\u00f3n ni perder versiones del mismo<\/p>","protected":false},"author":4,"featured_media":2293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[353],"tags":[309,310],"class_list":["post-2289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-de-aplicaciones","tag-git","tag-gitflow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gitflow es parte de tu equipo - Lacedemon<\/title>\n<meta name=\"description\" content=\"Gitflow es la soluci\u00f3n para poder trabajar en equipo en un proyecto sin perder informaci\u00f3n ni perder versiones del mismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lacedemon.com\/en\/gitflow-es-parte-de-tu-equipo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gitflow es parte de tu equipo - Lacedemon\" \/>\n<meta property=\"og:description\" content=\"Gitflow es la soluci\u00f3n para poder trabajar en equipo en un proyecto sin perder informaci\u00f3n ni perder versiones del mismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lacedemon.com\/en\/gitflow-es-parte-de-tu-equipo\/\" \/>\n<meta property=\"og:site_name\" content=\"Lacedemon\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-25T12:33:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T14:03:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lacedemon.com\/wp-content\/uploads\/2022\/03\/gitflow-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maria Jardon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@josemanuel_tech\" \/>\n<meta name=\"twitter:site\" content=\"@josemanuel_tech\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/\"},\"author\":{\"name\":\"Maria Jardon\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#\\\/schema\\\/person\\\/575125267593554f3da5d44bdb608b8f\"},\"headline\":\"Gitflow es parte de tu equipo\",\"datePublished\":\"2022-03-25T12:33:04+00:00\",\"dateModified\":\"2026-03-31T14:03:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/lacedemon.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/gitflow-1.png?fit=1640%2C924&ssl=1\",\"keywords\":[\"Git\",\"Gitflow\"],\"articleSection\":[\"Desarrollo de aplicaciones\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/\",\"url\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/\",\"name\":\"Gitflow es parte de tu equipo - Lacedemon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/lacedemon.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/gitflow-1.png?fit=1640%2C924&ssl=1\",\"datePublished\":\"2022-03-25T12:33:04+00:00\",\"dateModified\":\"2026-03-31T14:03:12+00:00\",\"description\":\"Gitflow es la soluci\u00f3n para poder trabajar en equipo en un proyecto sin perder informaci\u00f3n ni perder versiones del mismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lacedemon.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/gitflow-1.png?fit=1640%2C924&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lacedemon.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/gitflow-1.png?fit=1640%2C924&ssl=1\",\"width\":1640,\"height\":924,\"caption\":\"Git flow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/gitflow-es-parte-de-tu-equipo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/lacedemon.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/flutteracademy.app\\\/categoria\\\/uncategorized\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gitflow es parte de tu equipo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#website\",\"url\":\"https:\\\/\\\/lacedemon.com\\\/\",\"name\":\"Lacedemon\",\"description\":\"Consultor\u00eda e IA para pymes\",\"publisher\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lacedemon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#organization\",\"name\":\"lacedemon\",\"url\":\"https:\\\/\\\/lacedemon.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lacedemon.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-flutteracademy.png?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lacedemon.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo-flutteracademy.png?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200,\"caption\":\"lacedemon\"},\"image\":{\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/josemanuel_tech\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lacedemon.com\\\/#\\\/schema\\\/person\\\/575125267593554f3da5d44bdb608b8f\",\"name\":\"Maria Jardon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3025b2f3bef42fc25223853f0d3f22dfc5a6972e8845f7ec02c9e91dc9471c74?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3025b2f3bef42fc25223853f0d3f22dfc5a6972e8845f7ec02c9e91dc9471c74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3025b2f3bef42fc25223853f0d3f22dfc5a6972e8845f7ec02c9e91dc9471c74?s=96&d=mm&r=g\",\"caption\":\"Maria Jardon\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gitflow es parte de tu equipo - Lacedemon","description":"Gitflow es la soluci\u00f3n para poder trabajar en equipo en un proyecto sin perder informaci\u00f3n ni perder versiones del mismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lacedemon.com\/en\/gitflow-es-parte-de-tu-equipo\/","og_locale":"en_GB","og_type":"article","og_title":"Gitflow es parte de tu equipo - Lacedemon","og_description":"Gitflow es la soluci\u00f3n para poder trabajar en equipo en un proyecto sin perder informaci\u00f3n ni perder versiones del mismo","og_url":"https:\/\/lacedemon.com\/en\/gitflow-es-parte-de-tu-equipo\/","og_site_name":"Lacedemon","article_published_time":"2022-03-25T12:33:04+00:00","article_modified_time":"2026-03-31T14:03:12+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/lacedemon.com\/wp-content\/uploads\/2022\/03\/gitflow-1.png","type":"image\/png"}],"author":"Maria Jardon","twitter_card":"summary_large_image","twitter_creator":"@josemanuel_tech","twitter_site":"@josemanuel_tech","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/#article","isPartOf":{"@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/"},"author":{"name":"Maria Jardon","@id":"https:\/\/lacedemon.com\/#\/schema\/person\/575125267593554f3da5d44bdb608b8f"},"headline":"Gitflow es parte de tu equipo","datePublished":"2022-03-25T12:33:04+00:00","dateModified":"2026-03-31T14:03:12+00:00","mainEntityOfPage":{"@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/"},"wordCount":648,"publisher":{"@id":"https:\/\/lacedemon.com\/#organization"},"image":{"@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/gitflow-1.png?fit=1640%2C924&ssl=1","keywords":["Git","Gitflow"],"articleSection":["Desarrollo de aplicaciones"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/","url":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/","name":"Gitflow es parte de tu equipo - Lacedemon","isPartOf":{"@id":"https:\/\/lacedemon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/#primaryimage"},"image":{"@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/gitflow-1.png?fit=1640%2C924&ssl=1","datePublished":"2022-03-25T12:33:04+00:00","dateModified":"2026-03-31T14:03:12+00:00","description":"Gitflow es la soluci\u00f3n para poder trabajar en equipo en un proyecto sin perder informaci\u00f3n ni perder versiones del mismo","breadcrumb":{"@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/#primaryimage","url":"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/gitflow-1.png?fit=1640%2C924&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/gitflow-1.png?fit=1640%2C924&ssl=1","width":1640,"height":924,"caption":"Git flow"},{"@type":"BreadcrumbList","@id":"https:\/\/lacedemon.com\/gitflow-es-parte-de-tu-equipo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/lacedemon.com\/"},{"@type":"ListItem","position":2,"name":"Uncategorized","item":"https:\/\/flutteracademy.app\/categoria\/uncategorized\/"},{"@type":"ListItem","position":3,"name":"Gitflow es parte de tu equipo"}]},{"@type":"WebSite","@id":"https:\/\/lacedemon.com\/#website","url":"https:\/\/lacedemon.com\/","name":"Lacedemon","description":"Consultor\u00eda e IA para pymes","publisher":{"@id":"https:\/\/lacedemon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lacedemon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/lacedemon.com\/#organization","name":"lacedemon","url":"https:\/\/lacedemon.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lacedemon.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/10\/Logo-flutteracademy.png?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/10\/Logo-flutteracademy.png?fit=200%2C200&ssl=1","width":200,"height":200,"caption":"lacedemon"},"image":{"@id":"https:\/\/lacedemon.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/josemanuel_tech"]},{"@type":"Person","@id":"https:\/\/lacedemon.com\/#\/schema\/person\/575125267593554f3da5d44bdb608b8f","name":"Maria Jardon","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/3025b2f3bef42fc25223853f0d3f22dfc5a6972e8845f7ec02c9e91dc9471c74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3025b2f3bef42fc25223853f0d3f22dfc5a6972e8845f7ec02c9e91dc9471c74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3025b2f3bef42fc25223853f0d3f22dfc5a6972e8845f7ec02c9e91dc9471c74?s=96&d=mm&r=g","caption":"Maria Jardon"}}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lacedemon.com\/wp-content\/uploads\/2022\/03\/gitflow-1.png?fit=1640%2C924&ssl=1","_links":{"self":[{"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/posts\/2289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/comments?post=2289"}],"version-history":[{"count":4,"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/posts\/2289\/revisions"}],"predecessor-version":[{"id":2337,"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/posts\/2289\/revisions\/2337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/media\/2293"}],"wp:attachment":[{"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/media?parent=2289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/categories?post=2289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacedemon.com\/en\/wp-json\/wp\/v2\/tags?post=2289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}